{"id":247871,"date":"2025-10-07T09:17:07","date_gmt":"2025-10-07T07:17:07","guid":{"rendered":"https:\/\/cimne.com\/cimne-en-la-51a-reunion-anual-de-la-sociedad-nuclear-espanola-sne\/"},"modified":"2025-10-08T14:39:10","modified_gmt":"2025-10-08T12:39:10","slug":"cimne-en-la-51a-reunion-anual-de-la-sociedad-nuclear-espanola-sne","status":"publish","type":"post","link":"https:\/\/cimne.com\/es\/cimne-en-la-51a-reunion-anual-de-la-sociedad-nuclear-espanola-sne\/","title":{"rendered":"El CIMNE presenta avances en simulaci\u00f3n s\u00edsmica e innovaci\u00f3n en realidad virtual en el congreso anual de la Sociedad Nuclear Espa\u00f1ola"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-247829 size-full aligncenter\" style=\"text-align: center;\" src=\"https:\/\/cimne.com\/wp-content\/uploads\/2025\/10\/cimne-sne.png\" alt=\"CIMNE researchers in the CIMNE stand at the 51st Annual Meeting of the Spanish Nuclear Society (SNE)\" width=\"800\" height=\"450\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La <strong>51\u00aa Reuni\u00f3n Anual de la Sociedad Nuclear Espa\u00f1ola (SNE)<\/strong>, celebrada en C\u00e1ceres, volvi\u00f3 a consolidarse como el principal punto de encuentro del sector nuclear en Espa\u00f1a. Con <strong>694 asistentes, 248 ponencias, 42 sesiones t\u00e9cnicas, 23 expositores y 31 patrocinadores y colaboradores<\/strong>, el evento reuni\u00f3 a profesionales de la industria, la universidad y la investigaci\u00f3n para debatir sobre el presente y futuro de la energ\u00eda nuclear.<\/p>\n<p>CIMNE particip\u00f3 activamente con un <strong>stand propio<\/strong>, lo que nos permiti\u00f3 un contacto directo con la industria nuclear espa\u00f1ola y dar a conocer las <strong>capacidades desarrolladas en m\u00e1s de 30 a\u00f1os de colaboraci\u00f3n con el sector<\/strong>. El stand estuvo formado por investigadores del cl\u00faster en <a href=\"https:\/\/cimne.com\/es\/investigacion\/clusters-de-investigacion\/mecanica-estructural-particulas\/\">Mec\u00e1nica estructural y de part\u00edculas<\/a>, con una larga trayectoria en simulaci\u00f3n y seguridad nuclear.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247832 size-full\" style=\"text-align: center;\" src=\"https:\/\/cimne.com\/wp-content\/uploads\/2025\/10\/cimne-stand-sne.jpg\" alt=\"Exhibition stand of CIMNE showcasing their work on \u201cSimulation &amp; Innovation for Nuclear Safety.\u201d The stand features a blue background with icons and text highlighting areas such as advanced numerical modelling, structural safety, fluid dynamics, and regulatory support. A counter with brochures and promotional materials stands in front of the display.\" width=\"395\" height=\"450\" \/><\/p>\n<p style=\"text-align: center;\"><em>Stand del CIMNE en la 51\u00aa Reuni\u00f3n Anual de la SNE<\/em><\/p>\n<h3>Las contribuciones t\u00e9cnicas del CIMNE<\/h3>\n<p>Los investigadores del CIMNE aportaron su experiencia en la disciplina a trav\u00e9s de <strong>dos sesiones t\u00e9cnicas<\/strong>: \u201cSimulaci\u00f3n num\u00e9rica de edificios nucleares bajo sismo\u201d, presentada por el Dr. <a href=\"https:\/\/cimne.com\/es\/sobre-nosotros\/directorio\/perfil-miembro\/?id=551\">Fernando Rastellini Canela<\/a>, y \u201cCaracterizaci\u00f3n del riesgo s\u00edsmico en centrales nucleares\u201d, presentada por el Dr. Yeudy Felipe Vargas. <\/p>\n<p>Las ponencias introdujeron una metodolog\u00eda para generar registros s\u00edsmicos compatibles con los espectros objetivos mediante procesos de deconvoluci\u00f3n y ajuste espectral. Estas se\u00f1ales se aplicaron a modelos 3D de interacci\u00f3n suelo\u2013estructura (contacto fijo y deslizante), lo que permite obtener espectros s\u00edsmicos del edificio m\u00e1s completos y representativos. Los resultados son clave para <strong>mejorar la cuantificaci\u00f3n del impacto s\u00edsmico<\/strong> en los equipos y constituyen insumos cr\u00edticos para estudios de An\u00e1lisis de Seguridad Probabil\u00edstica (PSA).<\/p>\n<p>CIMNE obtuvo el <strong>primer premio<\/strong> entre m\u00e1s de 15 participantes con el <strong>p\u00f3ster<\/strong> \u201cSimulaci\u00f3n num\u00e9rica de edificios nucleares bajo sismo\u201d, presentado por <a href=\"https:\/\/cimne.com\/es\/sobre-nosotros\/directorio\/perfil-miembro\/?id=2441\">Cristhian Albert Padilla Lea\u00f1os<\/a>, que resumi\u00f3 en formato <strong>visual y multimedia<\/strong> los trabajos presentados en las sesiones t\u00e9cnicas.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247836 size-full\" style=\"text-align: center;\" src=\"https:\/\/cimne.com\/wp-content\/uploads\/2025\/10\/cimne-cristhian-padilla-poster.png\" alt=\"Cristhian Albert Padila presenting a scientific poster displayed on a vertical digital screen. The poster, from CIMNE, is titled \u201cSimulaci\u00f3n Num\u00e9rica de Edificios Nucleares bajo Sismo\u201d and includes colorful diagrams, graphs, and simulation results related to nuclear building performance under seismic conditions. The presentation takes place indoors on a wooden floor.\" width=\"800\" height=\"450\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cristhian Albert Padilla presentando el p\u00f3ster: \u00abSimulaci\u00f3n num\u00e9rica de edificios nucleares bajo sismo\u00bb<\/em><\/p>\n<p>En el stand del CIMNE, Mathias Proboste present\u00f3 la <strong>experiencia VR Nuclear<\/strong>, <strong>una herramienta inmersiva de realidad virtual<\/strong> que permite explorar la <strong>formaci\u00f3n de grietas en la respuesta no lineal por sobrecarga de los edificios nucleares de manera l\u00fadica y educativa<\/strong>. La experiencia muestra c\u00f3mo se originan y propagan las fisuras bajo cargas s\u00edsmicas crecientes, ofreciendo un entorno interactivo para comprender mejor el comportamiento estructural. Adem\u00e1s, evidencia el potencial de la realidad virtual para f<strong>ormaci\u00f3n de personal, seguridad en obra y planificaci\u00f3n de operaciones<\/strong> en instalaciones nucleares.<\/p>\n<p>Finalmente, <a href=\"https:\/\/cimne.com\/es\/sobre-nosotros\/directorio\/perfil-miembro\/?id=2308\"> Ana Mar\u00eda Zapata<\/a> particip\u00f3 en el <strong>taller <\/strong><strong><em>Women in Nuclear<\/em><\/strong> \u201cLa aventura de descubrir al cient\u00edfico que llevas dentro\u201d, junto a m\u00e1s de 50 estudiantes y 10 mentoras, para <strong>fomentar vocaciones STEM, compartir experiencias y reforzar el valor de las mentor\u00edas en una sociedad m\u00e1s preparada, diversa e innovadora<\/strong>.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-247839 size-full\" style=\"text-align: center;\" src=\"https:\/\/cimne.com\/wp-content\/uploads\/2025\/10\/cimne-win-sne.jpg\" alt=\"Group of women researchers participating in the \u201cMentoring WiN\u201d activity. The image includes the logos of \u201cWiN Spain\u201d and \u201cC\u00e1ceres 2025 \u2013 51st Annual SNE Meeting,\u201d indicating the event\u2019s context.\" width=\"450\" height=\"450\" \/><\/p>\n<p style=\"text-align: center;\"><em>Ana Mar\u00eda Zapata en el taller Women in Nuclear: \u00abLa aventura de descubrir al cient\u00edfico que llevas dentro\u00bb<\/em><\/p>\n<h3>Compromiso con la ciencia, la simulaci\u00f3n y la seguridad nuclear<\/h3>\n<p>Las metodolog\u00edas y experiencias presentadas se apoyan en <strong>normativa y gu\u00edas internacionales de referencia <\/strong>que sustentan nuestras capacidades en la generaci\u00f3n de espectros s\u00edsmicos y registros compatibles, el modelado avanzado de interacci\u00f3n suelo\u2013estructura, el desarrollo de espectros s\u00edsmicos de construcciones m\u00e1s completos y representativos, el dise\u00f1o s\u00edsmico de estructuras y SSC nucleares y la evaluaci\u00f3n probabil\u00edstica y metodolog\u00edas PSA.<\/p>\n<p>Con estas herramientas, CIMNE refuerza su compromiso de ofrecer soluciones integrales para la <strong>verificaci\u00f3n s\u00edsmica y la seguridad nuclear<\/strong>, combinando <strong>modelado num\u00e9rico avanzado, normativa internacional y transferencia tecnol\u00f3gica<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/ja.cat\/46svs\">\u00bfInteresado\/a? Programa una reuni\u00f3n con nuestro equipo.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La 51\u00aa Reuni\u00f3n Anual de la Sociedad Nuclear Espa\u00f1ola (SNE), celebrada en C\u00e1ceres, volvi\u00f3 a consolidarse como el principal punto de encuentro del sector nuclear en Espa\u00f1a. Con 694 asistentes, 248 ponencias, 42 sesiones t\u00e9cnicas, 23 expositores y 31 patrocinadores y colaboradores, el evento reuni\u00f3 a profesionales de la industria, la universidad y la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":247831,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","slim_seo":{"title":"El CIMNE presenta avances en simulaci\u00f3n s\u00edsmica e innovaci\u00f3n en realidad virtual en el congreso anual de la Sociedad Nuclear Espa\u00f1ola - CIMNE","description":"&nbsp; La 51\u00aa Reuni\u00f3n Anual de la Sociedad Nuclear Espa\u00f1ola (SNE) , celebrada en C\u00e1ceres, volvi\u00f3 a consolidarse como el principal punto de encuentro del sector"},"_slim_seo_primary_term_category":0,"_slim_seo_primary_term_post_tag":0,"footnotes":""},"categories":[50,329,379,377,93],"tags":[],"class_list":["post-247871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigacion-news","category-investigacion","category-mecanica-estructural-es","category-mecanica-estructural-y-de-particulas","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/posts\/247871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/comments?post=247871"}],"version-history":[{"count":0,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/posts\/247871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/media\/247831"}],"wp:attachment":[{"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/media?parent=247871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/categories?post=247871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cimne.com\/es\/wp-json\/wp\/v2\/tags?post=247871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}