{"id":244415,"date":"2025-05-06T13:45:13","date_gmt":"2025-05-06T11:45:13","guid":{"rendered":"https:\/\/cimne.com\/innovation\/innovation-units\/pre-post-and-digital-technologies-digit\/pre-i-postprocessament-gid\/"},"modified":"2026-07-01T12:37:34","modified_gmt":"2026-07-01T10:37:34","slug":"pre-i-postprocessament-gid","status":"publish","type":"page","link":"https:\/\/cimne.com\/ca\/innovacio\/unitats-innovacio\/tecnologies-pre-post-digitals-digit\/pre-i-postprocessament-gid\/","title":{"rendered":"Pre i Postprocessament (GiD)"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbIntro desktop\u00bb module_id=\u00bbfirst-section\u00bb _builder_version=\u00bb4.27.3&#8243; positioning=\u00bbnone\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d9d9d9&#8243; border_width_top=\u00bb1px\u00bb border_color_top=\u00bb#d9d9d9&#8243; border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#d9d9d9&#8243; border_width_left=\u00bb1px\u00bb border_color_left=\u00bb#d9d9d9&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider color=\u00bb#004996&#8243; divider_position=\u00bbcenter\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb85px\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbSubtitle\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bb0cd9f80c-570e-4179-9fd1-d5366dd9bb29&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\nTecnologies Pre, Post i Digitals (DIGIT)\n<p>[\/et_pb_text][et_pb_heading title=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF90aXRsZSIsInNldHRpbmdzIjp7ImJlZm9yZSI6IiIsImFmdGVyIjoiIn19@\u00bb admin_label=\u00bbH1&#8243; _builder_version=\u00bb4.27.5&#8243; _dynamic_attributes=\u00bbtitle\u00bb _module_preset=\u00bb4c5ef66f-50cd-42c5-b88c-a74fdcea313a\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text admin_label=\u00bbTitle\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bb6d55416f-9dec-40a9-9718-5879084be1a8&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Investigador principal<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbPrincipal Investigator\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbf199e95e-376a-4f66-b51b-482255312542&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Abel Coll<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bbBack button\u00bb _builder_version=\u00bb4.27.4&#8243; _dynamic_attributes=\u00bblink_option_url\u00bb _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbright\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb||25px||false|false\u00bb link_option_url=\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjExMCJ9fQ==@\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<span class=\"back\">Enrere<\/span>[\/et_pb_code][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/06\/cimne-gid-header.jpg\u00bb title_text=\u00bbcimne-gid-header\u00bb align=\u00bbcenter\u00bb force_fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb93ceb7f0-f4b5-45d5-902c-4c83237d3321&#8243; custom_margin=\u00bb||50px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbCluster Data Menu Desktop\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3fa56594-59c4-4608-b810-3a571a22796b\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|0px||0px|false|true\u00bb custom_padding_tablet=\u00bb50px|0%|||false|false\u00bb custom_padding_phone=\u00bb50px||||false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbVisi\u00f3 general\u00bb admin_label=\u00bbOverview\u00bb module_id=\u00bboverview-item\u00bb module_class=\u00bb tab-item\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbLora|600|on||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#444444&#8243; title_font_size=\u00bb1.1rem\u00bb title_line_height=\u00bb1.5rem\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbpadding-bottom: 16px;\u00bb global_colors_info=\u00bb{}\u00bb background__hover_enabled=\u00bboff|desktop\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#004996&#8243;][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|3%||0px|false|false\u00bb custom_padding_tablet=\u00bb50px|0%|||false|false\u00bb custom_padding_phone=\u00bb50px||||false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbRecerca\u00bb admin_label=\u00bbResearch\u00bb module_id=\u00bbresearch-item\u00bb module_class=\u00bb tab-item\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbLora|600|on||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#444444&#8243; title_font_size=\u00bb1.1rem\u00bb title_line_height=\u00bb1.5rem\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbpadding-bottom: 16px;\u00bb global_colors_info=\u00bb{}\u00bb background__hover_enabled=\u00bboff|desktop\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#004996&#8243;][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|0px||0px|false|true\u00bb custom_padding_tablet=\u00bb50px|0%|||false|false\u00bb custom_padding_phone=\u00bb50px||||false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbMembres\u00bb admin_label=\u00bbStaff\u00bb module_id=\u00bbstaff-item\u00bb module_class=\u00bbtab-item\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbLora|600|on||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#444444&#8243; title_font_size=\u00bb1.1rem\u00bb title_line_height=\u00bb1.5rem\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bbpadding-bottom: 16px;\u00bb global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#004996&#8243;][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb20px|0px||0px|false|true\u00bb custom_padding_tablet=\u00bb50px|0%|||false|false\u00bb custom_padding_phone=\u00bb50px||||false|false\u00bb custom_padding_last_edited=\u00bboff|desktop\u00bb border_width_right_tablet=\u00bb0px\u00bb border_width_right_phone=\u00bb0px\u00bb border_width_right_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbProjectes\u00bb admin_label=\u00bbProjects\u00bb module_id=\u00bbprojects-item\u00bb module_class=\u00bbtab-item\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbLora|600|on||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#444444&#8243; title_font_size=\u00bb1.1rem\u00bb title_line_height=\u00bb1.5rem\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bb    padding-bottom: 16px;\u00bb global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#004996&#8243;][\/et_pb_heading][et_pb_heading title=\u00bbPublicacions\u00bb disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbPublications\u00bb module_id=\u00bbpublications-item\u00bb module_class=\u00bbtab-item\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bbLora|600|on||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#444444&#8243; title_font_size=\u00bb1.1rem\u00bb title_line_height=\u00bb1.5rem\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb custom_css_main_element=\u00bb    padding-bottom: 16px;\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb title_text_color__hover_enabled=\u00bbon|hover\u00bb title_text_color__hover=\u00bb#004996&#8243;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbOverview Tab\u00bb module_class=\u00bboverview-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_margin=\u00bb|0px||0px|false|false\u00bb custom_padding=\u00bb50px|0px|50px|0px|true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#004996&#8243; text_font_size=\u00bb1.5rem\u00bb text_line_height=\u00bb1.8rem\u00bb width=\u00bb50%\u00bb width_tablet=\u00bb100%\u00bb width_phone=\u00bb100%\u00bb width_last_edited=\u00bbon|desktop\u00bb custom_margin=\u00bb||||true|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El Grup de Pre i Postprocessament (GiD) del CIMNE desenvolupa el GiD, un programari universal de pre i postprocessament que agilitza els fluxos de treball de simulaci\u00f3 amb eines avan\u00e7ades de geometria, generaci\u00f3 de malla i visualitzaci\u00f3 dissenyats per a la ci\u00e8ncia i l\u2019enginyeria.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bb1px Line Row\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb2500px\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb height=\u00bb0px\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_margin=\u00bb|0px||0px|false|false\u00bb custom_padding=\u00bb50px|0px|50px|0px|false|false\u00bb border_color_top=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/07\/cimne-gid-logo.jpg\u00bb title_text=\u00bbcimne-gid-logo\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El grup de recerca de Pre i Postprocessament (GiD) del CIMNE, integrat dins la Unitat d\u2019Innovaci\u00f3 DIGIT, es dedica exclusivament al desenvolupament i perfeccionament del <a href=\"https:\/\/www.gidsimulation.com\/\" target=\"_blank\" rel=\"noopener\">GiD<\/a>, un programari capdavanter de pre i postprocessament per a simulacions num\u00e8riques en ci\u00e8ncia i enginyeria. El GiD ofereix un entorn universal, adaptatiu i intu\u00eftiu que abasta tot el flux de la simulaci\u00f3 \u2014des del modelatge geom\u00e8tric i la generaci\u00f3 de malles fins a l\u2019assignaci\u00f3 de dades i la visualitzaci\u00f3 avan\u00e7ada de resultats. <\/p>\n<p><\/p>\n<p>L\u2019expertesa del grup abasta la geometria computacional, el desenvolupament d\u2019eines CAD i t\u00e8cniques robustes de generaci\u00f3 de malles, fet que permet gestionar de manera eficient models complexos amb diversos m\u00e8todes num\u00e8rics, com ara els d\u2019elements finits, de volums finits i els m\u00e8todes sense malla. El sistema CAD del GiD \u00e9s compatible amb superf\u00edcies NURBS, ofereix reparaci\u00f3 autom\u00e0tica de geometries i una integraci\u00f3 fluida amb una gran varietat de solucions de c\u00e0lcul, fet que el fa altament vers\u00e0til tant en entorns de recerca com en aplicacions industrials. <\/p>\n<p><\/p>\n<p>Un dels punts forts del Grup GiD rau en l\u2019atenci\u00f3 a la personalitzaci\u00f3 i la interoperabilitat. Els usuaris poden adaptar el programari a les seves necessitats espec\u00edfiques, automatitzar fluxos de treball de simulaci\u00f3 i connectar-hi, amb facilitat, solucions de c\u00e0lcul pr\u00f2pies o comercials. El grup tamb\u00e9 \u00e9s capdavanter en funcions avan\u00e7ades de postprocessament, amb potents capacitats de visualitzaci\u00f3 3D, animaci\u00f3 i exportaci\u00f3 de dades, tamb\u00e9 en escenaris de computaci\u00f3 d\u2019altes prestacions i a gran escala.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El GiD s\u2019ofereix tant per a finalitats cient\u00edfiques com empresarials, amb solucions a mida per a la formaci\u00f3, la recerca cient\u00edfica i les necessitats professionals.<\/p>\n<p><\/p>\n<p>Amb un comprom\u00eds amb la innovaci\u00f3 aplicada i la transfer\u00e8ncia de tecnologia, el grup GiD ofereix a enginyers i investigadors les eines per transformar dades complexes en coneixement aplicable, fent avan\u00e7ar m\u00faltiples disciplines de l\u2019enginyeria i contribuint a la missi\u00f3 del CIMNE de generar una transformaci\u00f3 digital amb impacte. El grup organitza convencions peri\u00f2diques, adre\u00e7ades a usuaris i desenvolupadors, per mostrar els darrers aven\u00e7os del programari GiD i recollir l\u2019aportaci\u00f3 de la comunitat. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bb1px Line Row\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb2500px\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb height=\u00bb0px\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbOverview CTA Tab\u00bb module_class=\u00bboverview-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; background_color=\u00bb#02a0a5&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; admin_label=\u00bbMem\u00f2ria anual\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_margin=\u00bb|0px||0px|false|false\u00bb custom_padding=\u00bb25px|0px|32px|0px|false|false\u00bb border_color_top=\u00bb#d9d9d9&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbObteniu el GiD\u00bb admin_label=\u00bbH2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbab708ca6-cc76-4f8a-b615-1ce4dd7a78fb\u00bb title_text_color=\u00bb#FFFFFF\u00bb title_line_height=\u00bb3rem\u00bb custom_margin=\u00bb0px||||false|false\u00bb title_line_height_tablet=\u00bb2.1rem\u00bb title_line_height_phone=\u00bb2.1rem\u00bb title_line_height_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; module_class=\u00bbcarrus\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bb#FFFFFF\u00bb text_font_size=\u00bb1.5rem\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Descobriu com el GiD pot potenciar les vostres necessitats de Pre i Postprocessament en recerca o sol\u00b7lucions comercials<\/p>\n<p>[\/et_pb_text][et_pb_code module_id=\u00bbpagination-container\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb32px||32px||true|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_code][et_pb_code admin_label=\u00bbCTA\u00bb module_class=\u00bbclickable-cta\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/www.gidsimulation.com\/\u00bb link_option_url_new_window=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"flecha-container-position-left\"><!-- [et_pb_line_break_holder] --> <!-- [et_pb_line_break_holder] --> <!-- [et_pb_line_break_holder] --> <span class=\"text-flecha-white\"> COMENCEU AVUI<\/span><!-- [et_pb_line_break_holder] --><\/div>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; module_class=\u00bbcarrus\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/06\/get-gid-cimne.jpg\u00bb title_text=\u00bbget-gid-cimne\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbOverview Img Tab\u00bb module_class=\u00bboverview-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_margin=\u00bb|0px||0px|false|false\u00bb custom_padding=\u00bb50px|0px|50px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/06\/gid-cimne-1.jpg\u00bb title_text=\u00bbgid-cimne-1&#8243; show_in_lightbox=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbimg-fit\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f4e2daa-a4c7-40db-b678-0b21ac6841bd\u00bb module_alignment=\u00bbcenter\u00bb height=\u00bb220px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/06\/gid-cimne-2.jpg\u00bb title_text=\u00bbgid-cimne-1&#8243; show_in_lightbox=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbimg-fit\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f4e2daa-a4c7-40db-b678-0b21ac6841bd\u00bb module_alignment=\u00bbcenter\u00bb height=\u00bb220px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/cimne.com\/wp-content\/uploads\/2025\/06\/gid-cimne-3.jpg\u00bb title_text=\u00bbgid-cimne-1&#8243; show_in_lightbox=\u00bbon\u00bb align=\u00bbcenter\u00bb module_class=\u00bbimg-fit\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb1f4e2daa-a4c7-40db-b678-0b21ac6841bd\u00bb module_alignment=\u00bbcenter\u00bb height=\u00bb220px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbResearch Tab\u00bb module_class=\u00bbresearch-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; admin_label=\u00bbOrganitzaci\u00f3 institucional i estructura administrativa\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; custom_padding=\u00bb0px|0px|32px|0px|false|false\u00bb locked=\u00bboff\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb\u00c0rees de recerca\u00bb admin_label=\u00bbH2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_text_color=\u00bb#004996&#8243; title_font_size=\u00bb2rem\u00bb title_line_height=\u00bb2rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; border_color_right=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbGeometria Computacional\u00bb admin_label=\u00bbComputational Geometry\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.8rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desenvolupament d\u2019eines de Disseny Assistit per Ordinador (CAD) per integrar-hi eines de simulaci\u00f3 num\u00e8rica.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00bbGeneraci\u00f3 de malla\u00bb admin_label=\u00bbMesh Generation\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.8rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desenvolupament i millora d\u2019eines de generaci\u00f3 de malles per a simulacions num\u00e8riques, tot donant resposta a les necessitats de tots els grups del CIMNE dedicats a la simulaci\u00f3 num\u00e8rica i a tots els usuaris de GiD.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00bbPostprocessament per Simulacions Num\u00e8riques\u00bb admin_label=\u00bbPostprocessing for Numerical Simulations\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.8rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Desenvolupament de t\u00e8cniques avan\u00e7ades de postprocessament per a simulacions num\u00e8riques, especialment en casos amb resultats massius i distribu\u00efts, orientats a arquitectures de Computaci\u00f3 d\u2019Altes Prestacions (HPC).<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00bbVisualitzaci\u00f3 Avan\u00e7ada\u00bb admin_label=\u00bbAdvanced Visualization\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.8rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>T\u00e8cniques avan\u00e7ades de visualitzaci\u00f3 3D adaptades a simulacions num\u00e8riques, tenint en compte models i conjunts de resultats de gran magnitud, aix\u00ed com solucions remotes que permetin l\u2019\u00fas de dispositius lleugers (m\u00f2bils) per visualitzar simulacions adaptades a arquitectures al n\u00favol.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00bbArquitectura de Software\u00bb title_tablet=\u00bbSoftware Architecture\u00bb title_phone=\u00bbSoftware Architecture\u00bb title_last_edited=\u00bbon|desktop\u00bb admin_label=\u00bbSoftware Architecture\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.8rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>\u2022 Disseny de la Interf\u00edcie Gr\u00e0fica d\u2019Usuari (GUI) per a programari de simulaci\u00f3, i personalitzaci\u00f3 de solvers per a la seva integraci\u00f3 a la plataforma de pre i postprocessament GiD.<br \/>\u2022 Adaptaci\u00f3 d\u2019arquitectures al n\u00favol per donar resposta a les necessitats del programari de simulaci\u00f3, i implementaci\u00f3 d\u2019una nova plataforma de simulacions basada en el paradigma de model de negoci Software as a Service (SaaS).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbStaff Tab\u00bb module_class=\u00bbstaff-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_code disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbWS staff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"staff-container\">\u00a0<\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbProjects Tab\u00bb module_class=\u00bbprojects-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbTabs Nav\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; module_id=\u00bbproject-items\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbProjectes en curs\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf021;||fa||900&#8243; icon_color=\u00bbrgba(2,160,165,0.5)\u00bb image_icon_width=\u00bb24px\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb admin_label=\u00bbOngoing projects\u00bb module_id=\u00bbongoing-projects-item\u00bb module_class=\u00bbprojects-nav-item nav-item-active\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb2be94eae-2349-4743-a4da-6a4100bff33f\u00bb header_level=\u00bbh6&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bbrgba(2,160,165,0.5)\u00bb header_font_size=\u00bb1.5rem\u00bb header_line_height=\u00bb1.8rem\u00bb image_icon_custom_margin=\u00bb|||30px|false|false\u00bb width=\u00bb100%\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb10px||0px||false|false\u00bb header_text_align_last_edited=\u00bboff|desktop\u00bb custom_css_blurb_image=\u00bbmargin-bottom: 0px;\u00bb custom_css_blurb_title=\u00bbpadding-left: 10px;\u00bb border_width_left=\u00bb1px\u00bb border_color_left=\u00bbrgba(2,160,165,0.5)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbProjectes finalitzats\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf058;||fa||400&#8243; icon_color=\u00bbrgba(2,160,165,0.5)\u00bb image_icon_width=\u00bb24px\u00bb icon_alignment=\u00bbleft\u00bb content_max_width=\u00bb100%\u00bb admin_label=\u00bbFinished projects\u00bb module_id=\u00bbfinished-projects-item\u00bb module_class=\u00bbprojects-nav-item \u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb2be94eae-2349-4743-a4da-6a4100bff33f\u00bb header_level=\u00bbh6&#8243; header_text_align=\u00bbleft\u00bb header_text_color=\u00bbrgba(2,160,165,0.5)\u00bb header_font_size=\u00bb1.5rem\u00bb header_line_height=\u00bb1.8rem\u00bb image_icon_custom_margin=\u00bb||0px|30px|false|false\u00bb width=\u00bb100%\u00bb module_alignment=\u00bbleft\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb10px||0px||false|false\u00bb header_text_align_last_edited=\u00bboff|desktop\u00bb custom_css_blurb_image=\u00bbmargin-bottom: 0px;\u00bb custom_css_blurb_title=\u00bbpadding-left: 10px;\u00bb border_width_left=\u00bb1px\u00bb border_color_left=\u00bbrgba(2,160,165,0.5)\u00bb global_colors_info=\u00bb{}\u00bb custom_css_blurb_image_last_edited=\u00bboff|desktop\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_code disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbWS projects\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"projects-container\">\u00a0<\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbPublications Tab\u00bb module_class=\u00bbpublications-content tab-content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; disabled=\u00bbon\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbCerca\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh6&#8243; title_text_color=\u00bb#02a0a5&#8243; title_font_size=\u00bb1.5rem\u00bb title_line_height=\u00bb1.9rem\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_code disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbWS publications filter\u00bb module_class=\u00bbrtd-layout\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<form id=\"publications-form\"><\/form>\n<p>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bbWS publications\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"publications-container\">\u00a0<\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbRelated News Global\u00bb module_class=\u00bbsection-news related-news-global\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbfed47f3e-3ebe-4259-a156-523c8e0b8966&#8243; background_color=\u00bbrgba(2,160,165,0.15)\u00bb positioning=\u00bbnone\u00bb border_color_all=\u00bb#d9d9d9&#8243; border_width_top=\u00bb1px\u00bb border_color_top=\u00bb#d9d9d9&#8243; border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#d9d9d9&#8243; border_width_left=\u00bb1px\u00bb border_color_left=\u00bb#d9d9d9&#8243; saved_tabs=\u00bball\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_heading title=\u00bbNot\u00edcies relacionades\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_text_color=\u00bb#004996&#8243; title_font_size=\u00bb3rem\u00bb title_line_height=\u00bb3rem\u00bb title_font_size_tablet=\u00bb2rem\u00bb title_font_size_phone=\u00bb2rem\u00bb title_font_size_last_edited=\u00bbon|phone\u00bb title_line_height_tablet=\u00bb2.1rem\u00bb title_line_height_phone=\u00bb2.1rem\u00bb title_line_height_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_blog posts_number=\u00bb1&#8243; admin_label=\u00bbSecondary news left\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bb3ed04698-5e33-431b-875a-29f1e90b0248&#8243; hover_enabled=\u00bb0&#8243; custom_css_main_element=\u00bbwidth: 100% !important;\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb include_categories=\u00bb288&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_blog][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_blog posts_number=\u00bb1&#8243; offset_number=\u00bb1&#8243; admin_label=\u00bbSecondary news right\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bb3ed04698-5e33-431b-875a-29f1e90b0248&#8243; hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb include_categories=\u00bb288,293&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbRelated News Bottom\u00bb module_id=\u00bbsection-news-bottom\u00bb _builder_version=\u00bb4.27.0&#8243; background_color=\u00bbrgba(2,160,165,0.15)\u00bb positioning=\u00bbnone\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb border_width_all=\u00bb1px\u00bb border_color_all=\u00bb#d9d9d9&#8243; border_width_top=\u00bb1px\u00bb border_color_top=\u00bb#d9d9d9&#8243; border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#d9d9d9&#8243; border_width_left=\u00bb1px\u00bb border_color_left=\u00bb#d9d9d9&#8243; collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbc7c24b71-68f1-4ba2-bc79-49dcbcce5ea1&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; custom_padding=\u00bb0px|3%||3%|false|false\u00bb border_width_right=\u00bb1px\u00bb border_color_right=\u00bb#d9d9d9&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bbon|on|off\u00bb admin_label=\u00bbEmpty element\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600||on|||||\u00bb text_text_color=\u00bb#444444&#8243; text_font_size=\u00bb1.1rem\u00bb text_line_height=\u00bb1.5rem\u00bb positioning=\u00bbrelative\u00bb position_origin_a=\u00bbbottom_left\u00bb position_origin_r=\u00bbbottom_left\u00bb width=\u00bb100%\u00bb height=\u00bb80px\u00bb custom_padding=\u00bb||4%||false|false\u00bb link_option_url=\u00bb#\u00bb text_text_color_tablet=\u00bb#000000&#8243; text_text_color_phone=\u00bb#000000&#8243; text_text_color_last_edited=\u00bbon|tablet\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bboff|desktop\u00bb module_alignment_tablet=\u00bbright\u00bb module_alignment_phone=\u00bbright\u00bb module_alignment_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bb56e57fde-4561-4cf6-a771-0a733a7201b1&#8243; custom_padding=\u00bb0px|3%||3%|false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbView More\u00bb module_class=\u00bbclickable-cta\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|600||on|||||\u00bb text_text_color=\u00bb#444444&#8243; text_font_size=\u00bb1.1rem\u00bb text_line_height=\u00bb1.5rem\u00bb link_text_color=\u00bb#444444&#8243; positioning=\u00bbrelative\u00bb position_origin_a=\u00bbbottom_left\u00bb position_origin_r=\u00bbbottom_left\u00bb width=\u00bb100%\u00bb height=\u00bb80px\u00bb custom_padding=\u00bb25px||||false|false\u00bb hover_enabled=\u00bb0&#8243; text_text_color_tablet=\u00bb#000000&#8243; text_text_color_phone=\u00bb#000000&#8243; text_text_color_last_edited=\u00bbon|desktop\u00bb link_text_color_tablet=\u00bb#444444&#8243; link_text_color_phone=\u00bb#444444&#8243; link_text_color_last_edited=\u00bbon|desktop\u00bb text_orientation_tablet=\u00bbleft\u00bb text_orientation_phone=\u00bbleft\u00bb text_orientation_last_edited=\u00bboff|desktop\u00bb module_alignment_tablet=\u00bbright\u00bb module_alignment_phone=\u00bbright\u00bb module_alignment_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb text_text_color__hover_enabled=\u00bboff|hover\u00bb text_text_color__hover=\u00bb#02a0a5&#8243; link_text_color__hover_enabled=\u00bbon|hover\u00bb link_text_color__hover=\u00bb#02a0a5&#8243; sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"flecha-container\"><span class=\"cuerpo-flecha\"> <\/span><br \/><span class=\"punta-flecha\"> <\/span><br \/><span class=\"text-flecha\"><a href=\"\/ca\/category\/news\/gid\">M\u00e9s Not\u00edcies<\/a><\/span><\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbWS attr\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px|0px|0px|0px|true|true\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbWS attr\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbae8970c0-a6e7-4d6b-aaa8-bc5db3303ca9&#8243; custom_margin=\u00bb0px|0px|0px|0px|true|true\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|true\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bbWS attr\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px|0px|0px|0px|true|true\u00bb custom_padding=\u00bb0px|0px|0px|0px|true|true\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div id=\"api-call\" class=\"rtd-page\" rtd-code=\"24\"><\/div>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tecnologies Pre, Post i Digitals (DIGIT)Investigador principalAbel CollEl Grup de Pre i Postprocessament (GiD) del CIMNE desenvolupa el GiD, un programari universal de pre i postprocessament que agilitza els fluxos de treball de simulaci\u00f3 amb eines avan\u00e7ades de geometria, generaci\u00f3 de malla i visualitzaci\u00f3 dissenyats per a la ci\u00e8ncia i l\u2019enginyeria.El grup de recerca de Pre i Postprocessament (GiD) del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":226545,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","slim_seo":{"title":"Pre i Postprocessament (GiD) - CIMNE","description":"Investigador principal Abel Coll Enrere El Grup de Pre i Postprocessament (GiD) del CIMNE desenvolupa el GiD, un programari universal de pre i postprocessament"},"footnotes":""},"class_list":["post-244415","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/pages\/244415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/comments?post=244415"}],"version-history":[{"count":0,"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/pages\/244415\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/pages\/226545"}],"wp:attachment":[{"href":"https:\/\/cimne.com\/ca\/wp-json\/wp\/v2\/media?parent=244415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}